﻿{"id":3579,"count":10,"description":"Las mesas elevadoras Hymo AX est\u00e1n disponibles con capacidades de elevaci\u00f3n de hasta 2000 kg y un recorrido de 800 mm. HYMO AX, equipada con un bastidor base con entrada de horquillas (accesorio opcional), se convierte en una soluci\u00f3n flexible cuando se requiere el desplazamiento de la plataforma entre sitios sin carga. Hymo AX es la opci\u00f3n ideal.  ","link":"https:\/\/hymo.com\/es\/lift-tables\/mesa-elevadora-ax\/","name":"Mesa elevadora AX","slug":"mesa-elevadora-ax","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":3,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesa elevadora AX - Hymo AB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hymo.com\/es\/lift-tables\/mesa-elevadora-ax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesa elevadora AX - Hymo AB\" \/>\n<meta property=\"og:description\" content=\"Las mesas elevadoras Hymo AX est\u00e1n disponibles con capacidades de elevaci\u00f3n de hasta 2000 kg y un recorrido de 800 mm. HYMO AX, equipada con un bastidor base con entrada de horquillas (accesorio opcional), se convierte en una soluci\u00f3n flexible cuando se requiere el desplazamiento de la plataforma entre sitios sin carga. Hymo AX es la opci\u00f3n ideal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hymo.com\/es\/lift-tables\/mesa-elevadora-ax\/\" \/>\n<meta property=\"og:site_name\" content=\"Hymo AB\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hymo.com\/wp-content\/uploads\/2018\/04\/Slider_201.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesa elevadora AX - Hymo AB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hymo.com\/es\/lift-tables\/mesa-elevadora-ax\/","og_locale":"es_ES","og_type":"article","og_title":"Mesa elevadora AX - Hymo AB","og_description":"Las mesas elevadoras Hymo AX est\u00e1n disponibles con capacidades de elevaci\u00f3n de hasta 2000 kg y un recorrido de 800 mm. HYMO AX, equipada con un bastidor base con entrada de horquillas (accesorio opcional), se convierte en una soluci\u00f3n flexible cuando se requiere el desplazamiento de la plataforma entre sitios sin carga. Hymo AX es la opci\u00f3n ideal.","og_url":"https:\/\/hymo.com\/es\/lift-tables\/mesa-elevadora-ax\/","og_site_name":"Hymo AB","og_image":[{"width":1100,"height":400,"url":"https:\/\/hymo.com\/wp-content\/uploads\/2018\/04\/Slider_201.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hymo.com\/es\/lift-tables\/mesa-elevadora-ax\/","url":"https:\/\/hymo.com\/es\/lift-tables\/mesa-elevadora-ax\/","name":"Mesa elevadora AX - Hymo AB","isPartOf":{"@id":"https:\/\/hymo.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/hymo.com\/es\/lift-tables\/mesa-elevadora-ax\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/hymo.com\/es\/lift-tables\/mesa-elevadora-ax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hymo.com\/es\/"},{"@type":"ListItem","position":2,"name":"Mesa elevadora AX"}]},{"@type":"WebSite","@id":"https:\/\/hymo.com\/es\/#website","url":"https:\/\/hymo.com\/es\/","name":"Hymo AB","description":"","publisher":{"@id":"https:\/\/hymo.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hymo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hymo.com\/es\/#organization","name":"Hymo AB","url":"https:\/\/hymo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hymo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hymo.com\/wp-content\/uploads\/2022\/02\/hymo.jpg","contentUrl":"https:\/\/hymo.com\/wp-content\/uploads\/2022\/02\/hymo.jpg","width":400,"height":400,"caption":"Hymo AB"},"image":{"@id":"https:\/\/hymo.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hymo.com\/es\/wp-json\/wp\/v2\/product_cat\/3579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hymo.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/hymo.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/hymo.com\/es\/wp-json\/wp\/v2\/product?product_cat=3579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}